{"id":396,"date":"2025-12-16T21:08:05","date_gmt":"2025-12-16T20:08:05","guid":{"rendered":"https:\/\/sesaepco.afrimvoe.net\/?p=396"},"modified":"2025-12-16T21:08:06","modified_gmt":"2025-12-16T20:08:06","slug":"en-memoire-kevin-un-premier-benevole-nous-a-quittes","status":"publish","type":"post","link":"https:\/\/sesaepco.afrimvoe.net\/index.php\/2025\/12\/16\/en-memoire-kevin-un-premier-benevole-nous-a-quittes\/","title":{"rendered":"EN M\u00c9MOIRE | K\u00e9vin, un premier b\u00e9n\u00e9vole nous a quitt\u00e9s."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tba\/1\/16\/1f54a.png\" alt=\"\ud83d\udd4a\ufe0f\"> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C&rsquo;est le c\u0153ur lourd que nous partageons la nouvelle du rappel \u00e0 Dieu de notre fr\u00e8re K\u00e9vin. Il \u00e9tait l&rsquo;un des <a><\/a>tout premiers b\u00e9n\u00e9voles du SESA \u00e0 Nsessoum, un pionnier \u00e0 la force inoubliable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Son engagement d\u00e9sint\u00e9ress\u00e9 a aid\u00e9 \u00e0 poser les bases de notre action dans cette communaut\u00e9. Nous perdons un fr\u00e8re, un mod\u00e8le de service.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous pr\u00e9sentons nos condol\u00e9ances les plus attrist\u00e9es \u00e0 sa famille et \u00e0 tous ceux qui l&rsquo;aimaient. Ton h\u00e9ritage vit en nous, K\u00e9vin.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Repose en paix.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.facebook.com\/hashtag\/sesa?__eep__=6&amp;__cft__[0]=AZafoc4IL4NIBd7MnYTXe5WibLcJ25b_mhErZd4Ahm0-85dXKYn0NFBc9EMJB_5q4cKYZpzc9YLEAMS-9AZ6UGh2qKWWLnZ98bP9MLFyce858Ia4ANBJ0QKjecjOqYDYRbX7j0kDJKjacpXRFKow8w_8&amp;__tn__=*NK-R\">#SESA<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/hommage?__eep__=6&amp;__cft__[0]=AZafoc4IL4NIBd7MnYTXe5WibLcJ25b_mhErZd4Ahm0-85dXKYn0NFBc9EMJB_5q4cKYZpzc9YLEAMS-9AZ6UGh2qKWWLnZ98bP9MLFyce858Ia4ANBJ0QKjecjOqYDYRbX7j0kDJKjacpXRFKow8w_8&amp;__tn__=*NK-R\">#Hommage<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/b%C3%A9n%C3%A9vole?__eep__=6&amp;__cft__[0]=AZafoc4IL4NIBd7MnYTXe5WibLcJ25b_mhErZd4Ahm0-85dXKYn0NFBc9EMJB_5q4cKYZpzc9YLEAMS-9AZ6UGh2qKWWLnZ98bP9MLFyce858Ia4ANBJ0QKjecjOqYDYRbX7j0kDJKjacpXRFKow8w_8&amp;__tn__=*NK-R\">#B\u00e9n\u00e9vole<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/nsessoum?__eep__=6&amp;__cft__[0]=AZafoc4IL4NIBd7MnYTXe5WibLcJ25b_mhErZd4Ahm0-85dXKYn0NFBc9EMJB_5q4cKYZpzc9YLEAMS-9AZ6UGh2qKWWLnZ98bP9MLFyce858Ia4ANBJ0QKjecjOqYDYRbX7j0kDJKjacpXRFKow8w_8&amp;__tn__=*NK-R\">#Nsessoum<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/souvenir?__eep__=6&amp;__cft__[0]=AZafoc4IL4NIBd7MnYTXe5WibLcJ25b_mhErZd4Ahm0-85dXKYn0NFBc9EMJB_5q4cKYZpzc9YLEAMS-9AZ6UGh2qKWWLnZ98bP9MLFyce858Ia4ANBJ0QKjecjOqYDYRbX7j0kDJKjacpXRFKow8w_8&amp;__tn__=*NK-R\">#Souvenir<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/service?__eep__=6&amp;__cft__[0]=AZafoc4IL4NIBd7MnYTXe5WibLcJ25b_mhErZd4Ahm0-85dXKYn0NFBc9EMJB_5q4cKYZpzc9YLEAMS-9AZ6UGh2qKWWLnZ98bP9MLFyce858Ia4ANBJ0QKjecjOqYDYRbX7j0kDJKjacpXRFKow8w_8&amp;__tn__=*NK-R\">#Service<\/a><a href=\"https:\/\/www.facebook.com\/hashtag\/condol%C3%A9ances?__eep__=6&amp;__cft__[0]=AZafoc4IL4NIBd7MnYTXe5WibLcJ25b_mhErZd4Ahm0-85dXKYn0NFBc9EMJB_5q4cKYZpzc9YLEAMS-9AZ6UGh2qKWWLnZ98bP9MLFyce858Ia4ANBJ0QKjecjOqYDYRbX7j0kDJKjacpXRFKow8w_8&amp;__tn__=*NK-R\">#Condol\u00e9ances<\/a> suivez ce lien pour acc\u00e9der aux souvenirs de la campagne \u00e0 Nsessoum durant l&rsquo;assembl\u00e9e g\u00e9n\u00e9rale o\u00f9 K\u00e9vin s&rsquo;est d\u00e9marqu\u00e9. <a href=\"https:\/\/www.facebook.com\/permalink.php?story_fbid=pfbid02RjijsR9sWrJwPt7o6GCJxtkT3UcgZndA8DkYbSTx7N4BC69xRiDCSfPoVJaJvvhel&amp;id=61580121043498&amp;__cft__[0]=AZafoc4IL4NIBd7MnYTXe5WibLcJ25b_mhErZd4Ahm0-85dXKYn0NFBc9EMJB_5q4cKYZpzc9YLEAMS-9AZ6UGh2qKWWLnZ98bP9MLFyce858Ia4ANBJ0QKjecjOqYDYRbX7j0kDJKjacpXRFKow8w_8&amp;__tn__=-UK-R\">https:\/\/www.facebook.com\/share\/p\/1Gm87SyMWy\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est le c\u0153ur lourd que nous partageons la nouvelle du rappel \u00e0 Dieu de notre fr\u00e8re K\u00e9vin. Il \u00e9tait l&rsquo;un des tout premiers b\u00e9n\u00e9voles du SESA \u00e0 Nsessoum, un pionnier \u00e0 la force inoubliable. Son engagement d\u00e9sint\u00e9ress\u00e9 a aid\u00e9 \u00e0 poser les bases de notre action dans cette communaut\u00e9. Nous perdons un fr\u00e8re, un mod\u00e8le [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":397,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[53,12,52,28],"class_list":["post-396","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-campagnes-sante","tag-adieu","tag-epco","tag-kevin","tag-nsessoum"],"_links":{"self":[{"href":"https:\/\/sesaepco.afrimvoe.net\/index.php\/wp-json\/wp\/v2\/posts\/396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sesaepco.afrimvoe.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sesaepco.afrimvoe.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sesaepco.afrimvoe.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sesaepco.afrimvoe.net\/index.php\/wp-json\/wp\/v2\/comments?post=396"}],"version-history":[{"count":1,"href":"https:\/\/sesaepco.afrimvoe.net\/index.php\/wp-json\/wp\/v2\/posts\/396\/revisions"}],"predecessor-version":[{"id":398,"href":"https:\/\/sesaepco.afrimvoe.net\/index.php\/wp-json\/wp\/v2\/posts\/396\/revisions\/398"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sesaepco.afrimvoe.net\/index.php\/wp-json\/wp\/v2\/media\/397"}],"wp:attachment":[{"href":"https:\/\/sesaepco.afrimvoe.net\/index.php\/wp-json\/wp\/v2\/media?parent=396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sesaepco.afrimvoe.net\/index.php\/wp-json\/wp\/v2\/categories?post=396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sesaepco.afrimvoe.net\/index.php\/wp-json\/wp\/v2\/tags?post=396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}